{"id":4673,"date":"2023-01-11T12:55:34","date_gmt":"2023-01-11T11:55:34","guid":{"rendered":"https:\/\/fumagallidanilo.com\/uncategorized\/january-detox-2\/"},"modified":"2026-07-28T22:47:40","modified_gmt":"2026-07-28T20:47:40","slug":"january-detox-2","status":"publish","type":"post","link":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/","title":{"rendered":"January Detox"},"content":{"rendered":"<p>And just like every year, after the unbridled overeating of the Christmas holidays, the guilt sets in&#8230;<br \/>\nInternational movements have even been created to make up for it and regain control of one\u2019s diet.<\/p>\n<p>The <a href=\"https:\/\/veganuary.com\/it\/partner\/essere-animali\/\"><strong>Veganuary<\/strong> <\/a>is the world\u2019s largest vegan movement, inspiring people to try a plant-based diet for the month of January and throughout the rest of the year.<br \/>\nBy signing up, you\u2019ll receive free helpful tips and access to delicious recipes and easy weekly meal plans.<\/p>\n<p>The <a href=\"https:\/\/alcoholchange.org.uk\/help-and-support\/managing-your-drinking\/dry-january\"><br \/>\n  <strong>Dry January<\/strong><br \/>\n<\/a>, on the other hand, is a campaign led by <a href=\"https:\/\/alcoholchange.org.uk\/\"><br \/>\n  <strong>Alcohol Change UK<\/strong><br \/>\n<\/a> in which people are urged to abstain from alcoholic beverages for the entire month of January.<\/p>\n<p>So, the resolution to get back in shape right away kicks in.<br \/>\nHow many gym memberships will be signed up for during these first few days of muddled thinking mixed with panic, only to be ignored without fail?<\/p>\n<p>Going from one extreme to the other is never a good strategy for our bodies.<br \/>\nThat\u2019s why we\u2019d like to recommend some seasonal products that are perfect for gradually regaining our physical and mental well-being without disrupting our lifestyle.<\/p>\n<p>You can find them <a href=\"https:\/\/fumagallidelivery.com\/1845-box\"><strong>HERE<\/strong> <\/a>in our dedicated boxes!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>And just like every year, after the unbridled overeating of the Christmas holidays, the guilt sets in&#8230; International movements have [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-4673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>January Detox - Fumagalli Danilo<\/title>\n<meta name=\"description\" content=\"Discover our boxes with seasonal fruits and vegetables to start the year with a balanced and detoxifying diet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"January Detox\" \/>\n<meta property=\"og:description\" content=\"Discover our boxes with seasonal fruits and vegetables to start the year with a balanced and detoxifying diet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fumagalli Danilo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fumagallidanilosrl\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-11T11:55:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T20:47:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2023\/01\/detox_01_s.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentina Pozzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentina Pozzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/\"},\"author\":{\"name\":\"Valentina Pozzi\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#\\\/schema\\\/person\\\/aaa17f07b3e36d5884eda90bcc287eaf\"},\"headline\":\"January Detox\",\"datePublished\":\"2023-01-11T11:55:34+00:00\",\"dateModified\":\"2026-07-28T20:47:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/\"},\"wordCount\":203,\"publisher\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fumagallidanilo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/detox_01_s.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/\",\"url\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/\",\"name\":\"January Detox - Fumagalli Danilo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fumagallidanilo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/detox_01_s.jpg\",\"datePublished\":\"2023-01-11T11:55:34+00:00\",\"dateModified\":\"2026-07-28T20:47:40+00:00\",\"description\":\"Discover our boxes with seasonal fruits and vegetables to start the year with a balanced and detoxifying diet.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/news-en-2\\\/january-detox-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fumagallidanilo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/detox_01_s.jpg\",\"contentUrl\":\"https:\\\/\\\/fumagallidanilo.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/detox_01_s.jpg\",\"width\":952,\"height\":714,\"caption\":\"Fumagalli Danilo Ingrosso Ortofrutta Limoni interi e a fette, con le foglie, sono disposti attorno alle tessere dello Scrabble che compongono la parola \u201cDETOX\u201d su una superficie di legno, mettendo in risalto la freschezza che ci si aspetta da un grossista ortofrutticolo come Fumagalli Danilo Besana in Brianza. Ristorazione Professionale - GDO - retail - privati\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/\",\"name\":\"Fumagalli Danilo\",\"description\":\"Commercio all&#039;ingrosso di prodotti ortofrutticoli\",\"publisher\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#organization\"},\"alternateName\":\"Fumagalli Danilo - Fresco e Buono\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#organization\",\"name\":\"Fumagalli Danilo Srl\",\"url\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fumagallidanilo.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Fumagalli_danilo_png.png\",\"contentUrl\":\"https:\\\/\\\/fumagallidanilo.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Fumagalli_danilo_png.png\",\"width\":2560,\"height\":932,\"caption\":\"Fumagalli Danilo Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fumagallidanilosrl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fumagalli-danilo\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/fumagallidanilosrl\\\/\",\"https:\\\/\\\/ordini2.fumagallidanilo.com\\\/catalogo.php\",\"https:\\\/\\\/fumagallidelivery.com\\\/\"],\"description\":\"Commercio all'ingrosso di prodotti ortofrutticoli.\",\"email\":\"info@fumagallidanilo.com\",\"telephone\":\"+39 0362918010\",\"legalName\":\"Fumagalli Danilo S.r.l.\",\"vatID\":\"05419200968\",\"taxID\":\"05419200968\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fumagallidanilo.com\\\/en\\\/#\\\/schema\\\/person\\\/aaa17f07b3e36d5884eda90bcc287eaf\",\"name\":\"Valentina Pozzi\",\"sameAs\":[\"Ensolab\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"January Detox - Fumagalli Danilo","description":"Discover our boxes with seasonal fruits and vegetables to start the year with a balanced and detoxifying diet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/","og_locale":"en_US","og_type":"article","og_title":"January Detox","og_description":"Discover our boxes with seasonal fruits and vegetables to start the year with a balanced and detoxifying diet.","og_url":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/","og_site_name":"Fumagalli Danilo","article_publisher":"https:\/\/www.facebook.com\/fumagallidanilosrl","article_published_time":"2023-01-11T11:55:34+00:00","article_modified_time":"2026-07-28T20:47:40+00:00","og_image":[{"width":952,"height":714,"url":"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2023\/01\/detox_01_s.jpg","type":"image\/jpeg"}],"author":"Valentina Pozzi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Valentina Pozzi","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/#article","isPartOf":{"@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/"},"author":{"name":"Valentina Pozzi","@id":"https:\/\/fumagallidanilo.com\/en\/#\/schema\/person\/aaa17f07b3e36d5884eda90bcc287eaf"},"headline":"January Detox","datePublished":"2023-01-11T11:55:34+00:00","dateModified":"2026-07-28T20:47:40+00:00","mainEntityOfPage":{"@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/"},"wordCount":203,"publisher":{"@id":"https:\/\/fumagallidanilo.com\/en\/#organization"},"image":{"@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2023\/01\/detox_01_s.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/","url":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/","name":"January Detox - Fumagalli Danilo","isPartOf":{"@id":"https:\/\/fumagallidanilo.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/#primaryimage"},"image":{"@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2023\/01\/detox_01_s.jpg","datePublished":"2023-01-11T11:55:34+00:00","dateModified":"2026-07-28T20:47:40+00:00","description":"Discover our boxes with seasonal fruits and vegetables to start the year with a balanced and detoxifying diet.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fumagallidanilo.com\/en\/news-en-2\/january-detox-2\/#primaryimage","url":"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2023\/01\/detox_01_s.jpg","contentUrl":"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2023\/01\/detox_01_s.jpg","width":952,"height":714,"caption":"Fumagalli Danilo Ingrosso Ortofrutta Limoni interi e a fette, con le foglie, sono disposti attorno alle tessere dello Scrabble che compongono la parola \u201cDETOX\u201d su una superficie di legno, mettendo in risalto la freschezza che ci si aspetta da un grossista ortofrutticolo come Fumagalli Danilo Besana in Brianza. Ristorazione Professionale - GDO - retail - privati"},{"@type":"WebSite","@id":"https:\/\/fumagallidanilo.com\/en\/#website","url":"https:\/\/fumagallidanilo.com\/en\/","name":"Fumagalli Danilo","description":"Commercio all&#039;ingrosso di prodotti ortofrutticoli","publisher":{"@id":"https:\/\/fumagallidanilo.com\/en\/#organization"},"alternateName":"Fumagalli Danilo - Fresco e Buono","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fumagallidanilo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fumagallidanilo.com\/en\/#organization","name":"Fumagalli Danilo Srl","url":"https:\/\/fumagallidanilo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fumagallidanilo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2025\/03\/Fumagalli_danilo_png.png","contentUrl":"https:\/\/fumagallidanilo.com\/wp-content\/uploads\/2025\/03\/Fumagalli_danilo_png.png","width":2560,"height":932,"caption":"Fumagalli Danilo Srl"},"image":{"@id":"https:\/\/fumagallidanilo.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fumagallidanilosrl","https:\/\/www.linkedin.com\/company\/fumagalli-danilo\/?viewAsMember=true","https:\/\/www.instagram.com\/fumagallidanilosrl\/","https:\/\/ordini2.fumagallidanilo.com\/catalogo.php","https:\/\/fumagallidelivery.com\/"],"description":"Commercio all'ingrosso di prodotti ortofrutticoli.","email":"info@fumagallidanilo.com","telephone":"+39 0362918010","legalName":"Fumagalli Danilo S.r.l.","vatID":"05419200968","taxID":"05419200968"},{"@type":"Person","@id":"https:\/\/fumagallidanilo.com\/en\/#\/schema\/person\/aaa17f07b3e36d5884eda90bcc287eaf","name":"Valentina Pozzi","sameAs":["Ensolab"]}]}},"_links":{"self":[{"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/posts\/4673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/comments?post=4673"}],"version-history":[{"count":1,"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/posts\/4673\/revisions"}],"predecessor-version":[{"id":4905,"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/posts\/4673\/revisions\/4905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/media\/2591"}],"wp:attachment":[{"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/media?parent=4673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/categories?post=4673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fumagallidanilo.com\/en\/wp-json\/wp\/v2\/tags?post=4673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}